{"id":367,"date":"2023-12-07T10:13:22","date_gmt":"2023-12-07T09:13:22","guid":{"rendered":"https:\/\/apparthotellerocher.com\/?page_id=367"},"modified":"2025-06-23T10:45:19","modified_gmt":"2025-06-23T08:45:19","slug":"port-racine","status":"publish","type":"page","link":"https:\/\/apparthotellerocher.com\/index.php\/port-racine\/","title":{"rendered":"Port-racine"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"367\" class=\"elementor elementor-367\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ea018e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ea018e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-458e3d7b\" data-id=\"458e3d7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3df53d2a elementor-widget elementor-widget-heading\" data-id=\"3df53d2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Port-racine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-724700f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"724700f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-42d05f65\" data-id=\"42d05f65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23da0d68 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"23da0d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8583\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEwLCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU4My1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8583-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8583-scaled-qgrlju4zygn8do5ldxawf6pozgx9s9b7p5ptpde5r4.jpg\" alt=\"197A8583\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8584\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTExLCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU4NC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8584-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8584-scaled-qgrlk7aqm558w7mh92zoe3e5av4es0rgeyumf8unc0.jpg\" alt=\"197A8584\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8594\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0LCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU5NC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8594-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8594-scaled-qgrll8wa7ikpsm3v5j8r5twl29z3bwwpw4y1mbawf4.jpg\" alt=\"197A8594\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8586\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEyLCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU4Ni1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8586-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8586-scaled-qgrlkjin2zlz354q9q9tsib50vg6k33ysnbxnucj34.jpg\" alt=\"197A8586\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8605\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE4LCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODYwNS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8605-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8605-scaled-qgrlmjw7p8d1x47lj3k3mi1mrjjg0s3aqlkbm5d7s0.jpg\" alt=\"197A8605\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8604\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE3LCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODYwNC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8604-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8604-scaled-qgrlm7ob8dwbq6pcig9y834n1j7o8pqscx30djvc0w.jpg\" alt=\"197A8604\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8602\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE2LCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODYwMi1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8602-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8602-scaled-qgrllxc357i66h4d6tt1ynqkiammw1lqnhwo3ianxc.jpg\" alt=\"197A8602\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8597\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1LCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU5Ny1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8597-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8597-scaled-qgrlll46od1fzjm466iwk8tksaav3z989tfcuwss68.jpg\" alt=\"197A8597\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23da0d68\" data-elementor-lightbox-title=\"197A8591\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEzLCJ1cmwiOiJodHRwczpcL1wvYXBwYXJ0aG90ZWxsZXJvY2hlci5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzEyXC8xOTdBODU5MS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMjNkYTBkNjgifQ%3D%3D\" href=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/2023\/12\/197A8591-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apparthotellerocher.com\/wp-content\/uploads\/elementor\/thumbs\/197A8591-scaled-qgrlkwodqo3zlolm4vylrezlc9nbjuk7iggqdpt0o0.jpg\" alt=\"197A8591\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e22715 elementor-widget elementor-widget-heading\" data-id=\"74e22715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Port-racine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b41a6b5 elementor-widget elementor-widget-text-editor\" data-id=\"b41a6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-teuzz-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-teuzz-1n7m0yu\"><div class=\"flex flex-col pb-9 text-sm\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-71\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\"><div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"8c299e4e-6eaa-4972-9dbe-0b9d07928964\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p>L&rsquo;appartement Port-Racine, situ\u00e9 \u00e0 l&rsquo;\u00e9tage du Rocher Appart H\u00f4tel, est une \u00e9chapp\u00e9e belle dans le plus petit port de France. Sur 30m\u00b2, il fusionne modernit\u00e9 et tradition, incarnant le charme normand. \u00c0 votre arriv\u00e9e, vous d\u00e9couvrirez un espace lumineux et a\u00e9r\u00e9, avec un espace bureau id\u00e9al pour se d\u00e9tendre ou planifier vos visites. La d\u00e9coration, agr\u00e9ment\u00e9e de cadres inspirants, vous transporte vers le pittoresque Port-Racine, un lieu embl\u00e9matique de la r\u00e9gion. La kitchenette moderne r\u00e9pond \u00e0 toutes vos envies culinaires, offrant la libert\u00e9 de cr\u00e9er vos propres mets.<\/p><p>Dans cet appartement, le calme et l&rsquo;\u00e9l\u00e9gance r\u00e8gnent. La chambre s\u00e9par\u00e9e promet un sommeil paisible et r\u00e9parateur, gr\u00e2ce \u00e0 un lit douillet et du linge de qualit\u00e9. La salle de bain combine style et praticit\u00e9, \u00e9quip\u00e9e pour assurer votre confort. Chaque aspect de Port-Racine a \u00e9t\u00e9 pens\u00e9 pour votre d\u00e9tente et bien-\u00eatre, faisant de ce lieu un havre id\u00e9al pour se ressourcer et explorer les charmes de la Normandie, avec une fen\u00eatre ouverte sur l&rsquo;un de ses tr\u00e9sors les plus charmants.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a6e8c7 elementor-widget elementor-widget-heading\" data-id=\"22a6e8c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Services<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2adbf426 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2adbf426\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a5aae91\" data-id=\"7a5aae91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41bba7db elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"41bba7db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Petit d\u00e9jeuner, servi en chambre<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wi-Fi gratuit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parking sur place<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-785589e6\" data-id=\"785589e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6628e00a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6628e00a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recharge voiture \u00e9lectrique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Terrain de p\u00e9tanque<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7406d728 elementor-widget elementor-widget-heading\" data-id=\"7406d728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Details<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11491950 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"11491950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pour 2 personnes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kitchenette \u00e9quip\u00e9es de : Plaque de cuisson, r\u00e9frig\u00e9rateur, micro ondes, cafeti\u00e8re Tassimo, bouilloire, grille pain<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Drap, serviette de toilette, torchon fournis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lit de 160 fabrication Fran\u00e7aise (possibilit\u00e9 d'avoir lit d'appoint et lit b\u00e9b\u00e9)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kit de bienvenue salle de bain (savon, gel douche)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square-full\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 512H0V0h512v512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kit de bienvenue cuisine (caf\u00e9, th\u00e9, sucre)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35ee911c\" data-id=\"35ee911c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-39b5ac94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39b5ac94\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-719ca1aa\" data-id=\"719ca1aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-240490a2 elementor-widget elementor-widget-heading\" data-id=\"240490a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c0 partir de :<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c151083 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3c151083\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">85\u20ac<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34ad2df2 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"34ad2df2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Par nuit<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5d33b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5d33b2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9f24985\" data-id=\"9f24985\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b89a82 elementor-widget elementor-widget-heading\" data-id=\"6b89a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Demande de r\u00e9servation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb5c1a9 elementor-widget elementor-widget-text-editor\" data-id=\"bb5c1a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPour garantir la disponibilit\u00e9 de votre s\u00e9jour, il est indispensable d&rsquo;appeler \u00e0 l&rsquo;avance pour effectuer une r\u00e9servation.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77be814 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"77be814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"tel:+33672525501\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-phone-outgoing-line\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nous appeler<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c78a851 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c78a851\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2373b0bb\" data-id=\"2373b0bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-175d8b61 elementor-widget elementor-widget-heading\" data-id=\"175d8b61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Plus d'informations<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24eace4a elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"24eace4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:0650399207\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">06 50 39 92 07 (Guilaine)<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:0672525501\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">06 72 52 55 01 (Laurence)<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 Chemin de La Tassinerie, 50700 Valognes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-599397c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"599397c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-108503e2\" data-id=\"108503e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57d6acaf elementor-widget elementor-widget-heading\" data-id=\"57d6acaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vous souhaitez r\u00e9server ? <a href=\"https:\/\/apparthotellerocher.com\/index.php\/acces-et-contact\/\">Contactez-nous<\/a>.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Port-racine L&rsquo;appartement Port-Racine, situ\u00e9 \u00e0 l&rsquo;\u00e9tage du Rocher Appart H\u00f4tel, est une \u00e9chapp\u00e9e belle dans le plus petit port de France. Sur 30m\u00b2, il fusionne modernit\u00e9 et tradition, incarnant le charme normand. \u00c0 votre arriv\u00e9e, vous d\u00e9couvrirez un espace lumineux et a\u00e9r\u00e9, avec un espace bureau id\u00e9al pour se d\u00e9tendre ou planifier vos visites. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_page_generator_pro_exclude":false,"_page_generator_pro_group":0,"_page_generator_pro_index":0,"footnotes":""},"class_list":["post-367","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/pages\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":40,"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/pages\/367\/revisions"}],"predecessor-version":[{"id":1312,"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/pages\/367\/revisions\/1312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/media\/203"}],"wp:attachment":[{"href":"https:\/\/apparthotellerocher.com\/index.php\/wp-json\/wp\/v2\/media?parent=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}